{"id":6160,"date":"2017-07-03T12:09:05","date_gmt":"2017-07-03T10:09:05","guid":{"rendered":"https:\/\/www.legipermis.com\/blog\/?p=6160"},"modified":"2021-08-20T11:51:33","modified_gmt":"2021-08-20T09:51:33","slug":"1er-juillet-2017-de-nouvelles-infractions-vraiment","status":"publish","type":"post","link":"https:\/\/www.legipermis.com\/blog\/2017\/07\/03\/1er-juillet-2017-de-nouvelles-infractions-vraiment\/","title":{"rendered":"1er juillet 2017 : de nouvelles infractions, vraiment ?"},"content":{"rendered":"<div style=\"text-align:right;\"><em style=\"font-size:12.9px;font-weight:bold;\" class=\"last-modified\">Mis \u00e0 jour le 20\/08\/2021.<\/em><\/div><p>Le 1er juillet c&#8217;est souvent une date choisie pour initier des changements plus ou moins importants. La route n&#8217;\u00e9chappe pas \u00e0 cette r\u00e8gle. <strong>Quels sont les changements du Code de la route au 01\/07\/2017 ? Quelles sont les nouvelles r\u00e8gles ?<\/strong> Sont-elles vraiment nouvelles ? Nous allons voir qu&#8217;en la mati\u00e8re les informations vont parfois trop vite comme le confirme le r\u00e9cent d\u00e9menti de la d\u00e9l\u00e9gation \u00e0 la S\u00e9curit\u00e9 Routi\u00e8re sur de fausses rumeurs.<!--more--><\/p>\n<h2>Nouvelles plaques d&#8217;immatriculation pour les 2-roues<\/h2>\n<p>Depuis le <strong>1er juillet 2017<\/strong>, tous les 2-roues (cyclos et motos), 3-roues motoris\u00e9s et les quads devront avoir une <strong>plaque d&#8217;immatriculation au <a href=\"\/blog\/2015\/02\/23\/plaque-dimmatriculation-des-motos-une-taille-unique\/\">format 210&#215;130 mm taille unique<\/a><\/strong>. Cette mesure \u00e9tait d\u00e9j\u00e0 en vigueur depuis le 1er juillet 2015 pour tous les v\u00e9hicules neufs ou d&#8217;occasion avec une nouvelle immatriculation. L&#8217;infraction concern\u00e9e est une contravention de classe 4 avec une <strong>amende de 135\u20ac<\/strong>. Aucun retrait de points en revanche. Il s&#8217;agit bien d&#8217;un communiqu\u00e9 officiel de la S\u00e9curit\u00e9 Routi\u00e8re.<\/p>\n<h2>Vignettes Crit&#8217;air obligatoires<\/h2>\n<p>Dans les zones \u00e0 circulation restreinte (<strong>ZCR<\/strong>), tous les v\u00e9hicules devront mettre la <a href=\"\/blog\/2016\/12\/30\/vignette-ecologique-obligatoire-au-16012017-a-paris\/\">vignette Crit\u2019Air<\/a> sous peine d&#8217;avoir une amende de 68 euros. A Paris, les v\u00e9hicules avec la vignette Crit\u2019Air 5 (dont les voitures diesel immatricul\u00e9e avant 2001) ne pourront plus rouler en semaine entre 8H00 et 20H00. Cette vignette est pour l&#8217;instant obligatoire \u00e0\u00a0Paris, Lyon, Villeurbanne et Grenoble mais sera progressivement \u00e9tendue \u00e0 d&#8217;autres communes. Rappelons que le prix de la vignette Crit&#8217;air est de 4.18\u20ac et qu&#8217;on peut la commander <a href=\"https:\/\/www.certificat-air.gouv.fr\/\" target=\"_blank\" rel=\"noopener\">sur le site du gouvernement<\/a>. L&#8217;infraction concern\u00e9e est une contravention de 3\u00e8me classe avec une <strong>amende de 68\u20ac<\/strong>. A noter que cette mesure \u00e9tait pr\u00e9vue de longue date rien de nouveau \u00e0 l&#8217;horizon.<\/p>\n<h2>Intox : se maquiller, manger ou fumer au volant ?<\/h2>\n<p>De nombreuses infractions \u00e9voqu\u00e9es \u00e0 l&#8217;occasion de ce changement du <strong>01\/07\/2017<\/strong> sont d\u00e9j\u00e0 pr\u00e9sentes depuis de nombreuses ann\u00e9es dans le Code de la route, qu&#8217;il s&#8217;agisse notamment de <a href=\"\/infractions\/fumer-au-volant.html\">fumer au volant en pr\u00e9sence d&#8217;un mineur<\/a>\u00a0ou de t\u00e9l\u00e9phoner au volant. D&#8217;autres sont purement fantaisistes comme le fait de manger un sandwich ou se maquillier. Il s&#8217;agit de <strong>fausses informations<\/strong> en tant que telles, la S\u00e9curit\u00e9 Routi\u00e8re a d&#8217;ailleurs publi\u00e9 un <a href=\"https:\/\/www.securite-routiere.gouv.fr\/actualites\/dementi-de-la-delegation-la-securite-routiere-0\" target=\"_blank\" rel=\"noopener\">d\u00e9menti officiel<\/a>\u00a0sur le sujet ce 2 juillet. De nombreux m\u00e9dias ont march\u00e9 dedans, semble-t-il, un peu rapidement.<\/p>\n<blockquote><p>Aucun article du Code de la route ne mentionne sp\u00e9cifiquement l\u2019interdiction d\u2019\u00e9couter de la musique, de manger un sandwich ou de chercher quelque chose dans la bo\u00eete \u00e0 gants du v\u00e9hicule.<\/p>\n<p>La seule modification intervenue le 1er juillet 2017 porte sur la taille r\u00e9glementaire des plaques de deux et trois-roues motoris\u00e9&#8230;<\/p><\/blockquote>\n<blockquote class=\"twitter-tweet\" data-lang=\"fr\">\n<p dir=\"ltr\" lang=\"fr\">&#x1f4cc; D\u00e9menti de la D\u00e9l\u00e9gat\u00b0 \u00e0 la <a href=\"https:\/\/twitter.com\/hashtag\/S%C3%A9curit%C3%A9Routi%C3%A8re?src=hash\">#S\u00e9curit\u00e9Routi\u00e8re<\/a> : pas d&#8217;\u00e9volution du code de la route au 1er juillet &#x2b07;&#xfe0f; &gt; <a href=\"https:\/\/t.co\/h4zjjmJlTM\">https:\/\/t.co\/h4zjjmJlTM<\/a> <a href=\"https:\/\/t.co\/lrGVqfGOcR\">pic.twitter.com\/lrGVqfGOcR<\/a><\/p>\n<p>\u2014 Minist\u00e8re Int\u00e9rieur (@Place_Beauvau) <a href=\"https:\/\/twitter.com\/Place_Beauvau\/status\/881509936441815041\">2 juillet 2017<\/a><\/p><\/blockquote>\n<p><script async=\"\" src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h3>Pour clarifier la situation :<\/h3>\n<ul>\n<li>La baisse de l\u2019<a href=\"\/permis-probatoire\/taux-alcool-jeune-conducteur.html\">alcool\u00e9mie pour les jeunes conducteurs<\/a> est entr\u00e9e en vigueur il y a 2ans, le 1er juillet 2015,<\/li>\n<li>Le fait de <a href=\"\/infractions\/telephone-au-volant.html\">t\u00e9l\u00e9phoner au volant<\/a> est sanctionn\u00e9 par la perte de 3 points et 135 euros d\u2019amende depuis janvier 2012,<\/li>\n<li>L\u2019<a href=\"\/infractions\/appareil-champ-vision-amende.html\">interdiction d\u2019un \u00e9cran dans le champ de vision<\/a> d\u2019un conducteur est inscrite dans le Code de la route depuis 2008.<\/li>\n<\/ul>\n<h3>Attention n\u00e9anmoins :<\/h3>\n<p>Si les informations sont all\u00e9es un peu vite en la mati\u00e8re, il convient de faire attention \u00e0 l&#8217;application de l&#8217;<a href=\"https:\/\/www.legifrance.gouv.fr\/codes\/article_lc\/LEGIARTI000019277061\/\">article R412-6 du Code de la route<\/a> permet tout de m\u00eame aux forces de Police ou de gendarmerie de sanctionner des comportements dangereux sur la route.<\/p>\n<blockquote><p>I.-Tout v\u00e9hicule en mouvement ou tout ensemble de v\u00e9hicules en mouvement doit avoir un conducteur. Celui-ci doit, \u00e0 tout moment, adopter un comportement prudent et respectueux envers les autres usagers des voies ouvertes \u00e0 la circulation. Il doit notamment faire preuve d&#8217;une prudence accrue \u00e0 l&#8217;\u00e9gard des usagers les plus vuln\u00e9rables.<\/p>\n<p>II.-Tout conducteur doit se tenir constamment en \u00e9tat et en position d&#8217;ex\u00e9cuter commod\u00e9ment et sans d\u00e9lai toutes les manoeuvres qui lui incombent. Ses possibilit\u00e9s de mouvement et son champ de vision ne doivent pas \u00eatre r\u00e9duits par le nombre ou la position des passagers, par les objets transport\u00e9s ou par l&#8217;apposition d&#8217;objets non transparents sur les vitres.<\/p>\n<p>III.-Le fait, pour tout conducteur, de contrevenir aux dispositions du II ci-dessus est puni de l&#8217;amende pr\u00e9vue pour les contraventions de la deuxi\u00e8me classe.<\/p>\n<p>IV.-En cas d&#8217;infraction aux dispositions du II ci-dessus, l&#8217;immobilisation du v\u00e9hicule peut \u00eatre prescrite dans les conditions pr\u00e9vues aux\u00a0articles L. 325-1 \u00e0 L. 325-3.<\/p><\/blockquote>\n<p>Potentiellement dans les tuyaux n\u00e9anmoins, un possible <a href=\"\/blog\/2017\/06\/01\/des-sanctions-plus-dures-contre-le-telephone-au-volant\/\">durcissement des sanctions pour le t\u00e9l\u00e9phone au volant<\/a>, qui n&#8217;est pour l&#8217;instant pas encore confirm\u00e9e pour l&#8217;ann\u00e9e 2017.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le 1er juillet c&#8217;est souvent une date choisie pour initier des changements plus ou moins importants. La route n&#8217;\u00e9chappe pas \u00e0 cette r\u00e8gle. <strong>Quels sont les changements du Code de la route au 01\/07\/2017 ? Quelles sont les nouvelles r\u00e8gles ?<\/strong> Sont-elles vraiment nouvelles ? Nous allons voir qu&#8217;en la mati\u00e8re les informations vont parfois trop vite comme le confirme le r\u00e9cent d\u00e9menti de la d\u00e9l\u00e9gation \u00e0 la S\u00e9curit\u00e9 Routi\u00e8re sur de fausses rumeurs.\u00a0[&#8230;]<\/p>\n","protected":false},"author":3,"featured_media":6164,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[491,132,181,69,278,404,357],"class_list":["post-6160","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-legislation","tag-1er-juillet-2017","tag-2-roues-motorises","tag-legislation-2","tag-moto","tag-plaque-dimmatriculation","tag-telephone-au-volant","tag-vignette","post-1","odd"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.legipermis.com\/blog\/wp-json\/wp\/v2\/posts\/6160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.legipermis.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.legipermis.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.legipermis.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.legipermis.com\/blog\/wp-json\/wp\/v2\/comments?post=6160"}],"version-history":[{"count":0,"href":"https:\/\/www.legipermis.com\/blog\/wp-json\/wp\/v2\/posts\/6160\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.legipermis.com\/blog\/wp-json\/wp\/v2\/media\/6164"}],"wp:attachment":[{"href":"https:\/\/www.legipermis.com\/blog\/wp-json\/wp\/v2\/media?parent=6160"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.legipermis.com\/blog\/wp-json\/wp\/v2\/categories?post=6160"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.legipermis.com\/blog\/wp-json\/wp\/v2\/tags?post=6160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}