{"id":12193,"date":"2023-07-17T12:28:49","date_gmt":"2023-07-17T10:28:49","guid":{"rendered":"https:\/\/www.legipermis.com\/blog\/?p=12193"},"modified":"2023-07-18T10:48:29","modified_gmt":"2023-07-18T08:48:29","slug":"homicide-routier-definition-cisr","status":"publish","type":"post","link":"https:\/\/www.legipermis.com\/blog\/2023\/07\/17\/homicide-routier-definition-cisr\/","title":{"rendered":"Homicide routier : D\u00e9finition de la nouvelle mesure du gouvernement"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Le gouvernement d&#8217;Elisabeth Borne a annonc\u00e9 un changement de terminologie pour les accidents de la route avec des morts ou des bless\u00e9s dans certaines situations. Le terme &#8220;homicide involontaire&#8221; sera d\u00e9sormais remplac\u00e9 par &#8220;homicide routier&#8221;. Cette modification, principalement s\u00e9mantique, ne modifie pas les sanctions pr\u00e9vues par le Code p\u00e9nal et le Code de la route.<\/p>\n\n\n\n<!--more-->\n\n\n\n<h2 class=\"wp-block-heading\">Une demande des associations<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ce changement r\u00e9pond aux demandes des associations de victimes de la route, qui \u00e9taient choqu\u00e9es par la qualification d&#8217;homicide involontaire notamment apr\u00e8s de multiples affaires tr\u00e8s m\u00e9diatiques. La nouvelle terminologie s&#8217;appliquera \u00e9galement aux blessures, qui seront d\u00e9sormais qualifi\u00e9es de &#8220;routi\u00e8res&#8221; et non plus d'&#8221;involontaires&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Certains auraient aussi voulu un alourdissement des sanctions. Aujourd&#8217;hui, un &#8220;homicide involontaire&#8221; avec de multiples circonstances aggravantes, c\u2019est 10 ans de prison et 150 000 euros d\u2019amende (peines maximales th\u00e9oriques pr\u00e9vues pour plusieurs circonstances aggravantes d\u00e9finies dans l&#8217;<a href=\"https:\/\/www.legifrance.gouv.fr\/codes\/article_lc\/LEGIARTI000037113898\" target=\"_blank\" rel=\"noreferrer noopener\">article L232-2<\/a>&nbsp;du Code de la route<em>&nbsp;<\/em>reprenant l&#8217;article 221-6-1 du Code p\u00e9nal, on parle d&#8217;un quantum de peine). <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><noscript><img decoding=\"async\" width=\"1024\" height=\"535\" src=\"https:\/\/www.legipermis.com\/blog\/wp-content\/uploads\/2023\/07\/CISR-17-juillet-2023-1024x535.webp\" alt=\"CISR 17 Juillet 2023\" class=\"wp-image-12212\" srcset=\"https:\/\/www.legipermis.com\/blog\/wp-content\/uploads\/2023\/07\/CISR-17-juillet-2023-1024x535.webp 1024w, https:\/\/www.legipermis.com\/blog\/wp-content\/uploads\/2023\/07\/CISR-17-juillet-2023-300x157.webp 300w, https:\/\/www.legipermis.com\/blog\/wp-content\/uploads\/2023\/07\/CISR-17-juillet-2023-150x78.webp 150w, https:\/\/www.legipermis.com\/blog\/wp-content\/uploads\/2023\/07\/CISR-17-juillet-2023-768x401.webp 768w, https:\/\/www.legipermis.com\/blog\/wp-content\/uploads\/2023\/07\/CISR-17-juillet-2023.webp 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\"><\/noscript><img decoding=\"async\" width=\"1024\" height=\"535\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20viewBox%3D%220%200%201024%20535%22%3E%3C%2Fsvg%3E\" alt=\"CISR 17 Juillet 2023\" class=\"wp-image-12212 lazyload\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20viewBox%3D%220%200%201024%20535%22%3E%3C%2Fsvg%3E 1024w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" data-srcset=\"https:\/\/www.legipermis.com\/blog\/wp-content\/uploads\/2023\/07\/CISR-17-juillet-2023-1024x535.webp 1024w, https:\/\/www.legipermis.com\/blog\/wp-content\/uploads\/2023\/07\/CISR-17-juillet-2023-300x157.webp 300w, https:\/\/www.legipermis.com\/blog\/wp-content\/uploads\/2023\/07\/CISR-17-juillet-2023-150x78.webp 150w, https:\/\/www.legipermis.com\/blog\/wp-content\/uploads\/2023\/07\/CISR-17-juillet-2023-768x401.webp 768w, https:\/\/www.legipermis.com\/blog\/wp-content\/uploads\/2023\/07\/CISR-17-juillet-2023.webp 1200w\" data-src=\"https:\/\/www.legipermis.com\/blog\/wp-content\/uploads\/2023\/07\/CISR-17-juillet-2023-1024x535.webp\"><figcaption class=\"wp-element-caption\">Compte-rendu du comit\u00e9 interminist\u00e9riel de la s\u00e9curit\u00e9 routi\u00e8re (CISR) &#8211; Source: vid\u00e9o francetvinfo.<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Des \u00e9lus du groupe Les R\u00e9publicains ont d\u00e9pos\u00e9 une proposition de loi pour r\u00e9clamer des peines deux fois plus lourdes, jusqu\u2019\u00e0 20 ans de prison et 300 000 euros d\u2019amende.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Malgr\u00e9 ce changement, les peines encourues restent les m\u00eames : 5 ans pour un homicide simple et 10 ans en cas de circonstance aggravante. Cependant, certaines associations de victimes ont exprim\u00e9 leur d\u00e9ception, esp\u00e9rant des sanctions plus s\u00e9v\u00e8res et des mesures d&#8217;accompagnement plus pouss\u00e9es.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><noscript><img decoding=\"async\" src=\"https:\/\/www.legipermis.com\/blog\/wp-content\/uploads\/2023\/07\/5BEBD98D-7A73-48A8-B7FC-8EF396ED144F-1024x1024.jpeg\" alt class=\"wp-image-12225\" width=\"719\" height=\"719\" srcset=\"https:\/\/www.legipermis.com\/blog\/wp-content\/uploads\/2023\/07\/5BEBD98D-7A73-48A8-B7FC-8EF396ED144F-1024x1024.jpeg 1024w, https:\/\/www.legipermis.com\/blog\/wp-content\/uploads\/2023\/07\/5BEBD98D-7A73-48A8-B7FC-8EF396ED144F-300x300.jpeg 300w, https:\/\/www.legipermis.com\/blog\/wp-content\/uploads\/2023\/07\/5BEBD98D-7A73-48A8-B7FC-8EF396ED144F-150x150.jpeg 150w, https:\/\/www.legipermis.com\/blog\/wp-content\/uploads\/2023\/07\/5BEBD98D-7A73-48A8-B7FC-8EF396ED144F-768x768.jpeg 768w, https:\/\/www.legipermis.com\/blog\/wp-content\/uploads\/2023\/07\/5BEBD98D-7A73-48A8-B7FC-8EF396ED144F.jpeg 1280w\" sizes=\"(max-width: 719px) 100vw, 719px\"><\/noscript><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20viewBox%3D%220%200%20719%20719%22%3E%3C%2Fsvg%3E\" alt class=\"wp-image-12225 lazyload\" width=\"719\" height=\"719\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20viewBox%3D%220%200%20719%20719%22%3E%3C%2Fsvg%3E 719w\" sizes=\"(max-width: 719px) 100vw, 719px\" data-srcset=\"https:\/\/www.legipermis.com\/blog\/wp-content\/uploads\/2023\/07\/5BEBD98D-7A73-48A8-B7FC-8EF396ED144F-1024x1024.jpeg 1024w, https:\/\/www.legipermis.com\/blog\/wp-content\/uploads\/2023\/07\/5BEBD98D-7A73-48A8-B7FC-8EF396ED144F-300x300.jpeg 300w, https:\/\/www.legipermis.com\/blog\/wp-content\/uploads\/2023\/07\/5BEBD98D-7A73-48A8-B7FC-8EF396ED144F-150x150.jpeg 150w, https:\/\/www.legipermis.com\/blog\/wp-content\/uploads\/2023\/07\/5BEBD98D-7A73-48A8-B7FC-8EF396ED144F-768x768.jpeg 768w, https:\/\/www.legipermis.com\/blog\/wp-content\/uploads\/2023\/07\/5BEBD98D-7A73-48A8-B7FC-8EF396ED144F.jpeg 1280w\" data-src=\"https:\/\/www.legipermis.com\/blog\/wp-content\/uploads\/2023\/07\/5BEBD98D-7A73-48A8-B7FC-8EF396ED144F-1024x1024.jpeg\"><figcaption class=\"wp-element-caption\">Source: Compte twitter de la premi\u00e8re ministre Elisabeth Borne.<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Il est notamment \u00e9voqu\u00e9 le temps du traitement p\u00e9nal des dossiers, jug\u00e9 beaucoup trop long par tous.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">D\u00e9finition de l&#8217;homicide routier retenue par le gouvernement<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La qualification d&#8217;homicide routier sera retenue \u00e0 la place d&#8217;homicide involontaire <\/strong>m\u00eame sans circonstance aggravante<strong>, <\/strong>c&#8217;est-\u00e0-dire d\u00e9s lors qu&#8217;un accident a caus\u00e9 la mort m\u00eame sans les infractions comme le <a href=\"https:\/\/www.legipermis.com\/infractions\/alcool-permis-conduire.html\" target=\"_blank\" rel=\"noopener\" title>d\u00e9lit d&#8217;alcool au volant<\/a> et de <a href=\"https:\/\/www.legipermis.com\/infractions\/amende-stupefiant-volant.html#menu6\" target=\"_blank\" rel=\"noopener\" title>conduite sous l&#8217;empire de produits stup\u00e9fiants<\/a> (THC cannabis). <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">&#8221; L\u2019ajout d\u2019un tel qualificatif \u00e0 haute valeur symbolique permet de nommer plus pr\u00e9cis\u00e9ment l\u2019infraction au sein de l\u2019article d\u2019incrimination, sans pour autant att\u00e9nuer l\u2019effet juridique. &#8221; <\/p>\n<cite><em>CISR du 17 juillet 2023.<\/em><\/cite><\/blockquote>\n\n\n\n<div style=\"margin-bottom:4px;max-width:730px;text-align:center;\">\n\t<!-- responsive blog legipermis avant bl -->\n\t<ins class=\"adsbygoogle\" style=\"display:block\" data-ad-client=\"ca-pub-0319615741565724\" data-ad-slot=\"3542437151\" data-ad-format=\"auto\" id=\"top-ad-responsive-blog\"><\/ins>\n\t<script>\n\t(tarteaucitron.job = tarteaucitron.job || []).push('adsense');\n\t(adsbygoogle = window.adsbygoogle || []).push({});\n\t<\/script>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\">R\u00e9union du Comit\u00e9 interminist\u00e9riel de la s\u00e9curit\u00e9 routi\u00e8re (CISR)<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Un <a href=\"https:\/\/www.legipermis.com\/blog\/2023\/07\/17\/cisr-toutes-les-annonces\/\" title=\"CISR 2023 : Toutes les annonces de s\u00e9curit\u00e9 routi\u00e8re\">Comit\u00e9 interminist\u00e9riel de la s\u00e9curit\u00e9 routi\u00e8re (CISR) est r\u00e9uni ce lundi 17 juillet 2023<\/a> afin d&#8217;ent\u00e9riner cette annonce. <\/p>\n\n\n\n<blockquote class=\"twitter-tweet\"><p lang=\"fr\" dir=\"ltr\">EN DIRECT | Prise de parole de la Premi\u00e8re ministre <a href=\"https:\/\/twitter.com\/Elisabeth_Borne?ref_src=twsrc%5Etfw\">@Elisabeth_Borne<\/a> \u00e0 la suite de sa visite du centre de R\u00e9adaptation de Coubert. <a href=\"https:\/\/t.co\/UeJS8O0pXd\">https:\/\/t.co\/UeJS8O0pXd<\/a><\/p>&mdash; Gouvernement (@gouvernementFR) <a href=\"https:\/\/twitter.com\/gouvernementFR\/status\/1680911140119773186?ref_src=twsrc%5Etfw\">July 17, 2023<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n\n\n\n<p class=\"wp-block-paragraph\">Parall\u00e8lement \u00e0 ce changement s\u00e9mantique, le gouvernement a annonc\u00e9 vouloir \u00abrendre obligatoire\u00bb la suspension du permis en cas de conduite sous l\u2019empire de stup\u00e9fiants. Une mesure d\u00e9j\u00e0 largement pratiqu\u00e9e au niveau administratif et de la justice. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En outre, la premi\u00e8re ministre Elisabeth Borne a annonc\u00e9&nbsp;&#8220;la suspension du permis&nbsp;le temps d&#8217;une v\u00e9rification m\u00e9dicale d&#8217;aptitude \u00e0 la conduite&#8221; en cas d&#8217;une infraction au Code de la route dont l&#8217;origine pourrait \u00eatre un probl\u00e8me m\u00e9dical.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En parall\u00e8le, le ministre de l&#8217;int\u00e9rieur Gerald Darmanin annonc\u00e9 renforcer les sanctions administratives \u00e0 l&#8217;encontre des conducteurs ayant consomm\u00e9 de la drogue :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>L&#8217;augmentation du nombre de points perdus pour une consommation de stup\u00e9fiant notamment avec de l&#8217;alcool, passant d&#8217;un retrait de 6 points \u00e0 8 points (\u00e0 confirmer avec les textes) ;<\/li>\n\n\n\n<li>La suspension automatique du permis en cas de conduite sous stup\u00e9fiants comme l&#8217;a annonc\u00e9 la premi\u00e8re ministre dans son propos liminaire ;<\/li>\n\n\n\n<li>Une immobilisation du v\u00e9hicule qui plus syst\u00e9matiquement appliqu\u00e9e qu&#8217;auparavant a priori ;<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Tout ceci sera confirm\u00e9 dans notre article d\u00e9di\u00e9e aux conclusions du CISR.\/<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ces mesures interviennent apr\u00e8s une ann\u00e9e en demi-teinte en mati\u00e8re de bilan de l&#8217;accidentologie. En 2022, <a href=\"https:\/\/www.legipermis.com\/blog\/2023\/06\/01\/bilan-securite-routiere-2022\/\" target=\"_blank\" rel=\"noopener\" title>3267 personnes sont mortes sur les routes de France<\/a> m\u00e9tropolitaine, un bilan \u00e0 un niveau stable par rapport \u00e0 2019, derni\u00e8re ann\u00e9e de r\u00e9f\u00e9rence avant la pand\u00e9mie.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\nLe gouvernement d&#8217;Elisabeth Borne a annonc\u00e9 un changement de terminologie pour les accidents de la route avec des morts ou des bless\u00e9s dans certaines situations. Le terme &#8220;homicide involontaire&#8221; sera d\u00e9sormais remplac\u00e9 par &#8220;homicide routier&#8221;. Cette modification, principalement s\u00e9mantique, ne modifie pas les sanctions pr\u00e9vues par le Code p\u00e9nal et le Code de la route.<\/p>\n<p>\u00a0[&#8230;]<\/p>\n","protected":false},"author":3,"featured_media":12206,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[113,685,686,687,70],"class_list":["post-12193","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-legislation","tag-code-de-la-route","tag-code-penal","tag-homicide-involontaire","tag-homicide-routier","tag-securite-routiere-2","post-1","odd"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Le gouvernement d&#039;Elisabeth Borne a annonc\u00e9 un changement de terminologie pour les accidents de la route avec des morts ou des bless\u00e9s dans certaines situations. Le terme &quot;homicide involontaire&quot; sera d\u00e9sormais remplac\u00e9 par &quot;homicide routier&quot;. Cette modification, principalement s\u00e9mantique, ne modifie pas les sanctions pr\u00e9vues par le Code p\u00e9nal et le Code de la route.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Fr\u00e9d\u00e9ric Darne\"\/>\n\t<meta name=\"keywords\" content=\"code de la route,code p\u00e9nal,homicide involontaire,homicide routier,s\u00e9curit\u00e9 routi\u00e8re\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.legipermis.com\/blog\/2023\/07\/17\/homicide-routier-definition-cisr\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Auto, moto, s\u00e9curit\u00e9 routi\u00e8re et permis | blog LegiPermis |\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Homicide routier : D\u00e9finition de la nouvelle mesure du gouvernement - LegiPermis\" \/>\n\t\t<meta property=\"og:description\" content=\"Le gouvernement d&#039;Elisabeth Borne a annonc\u00e9 un changement de terminologie pour les accidents de la route avec des morts ou des bless\u00e9s dans certaines situations. Le terme &quot;homicide involontaire&quot; sera d\u00e9sormais remplac\u00e9 par &quot;homicide routier&quot;. Cette modification, principalement s\u00e9mantique, ne modifie pas les sanctions pr\u00e9vues par le Code p\u00e9nal et le Code de la route.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.legipermis.com\/blog\/2023\/07\/17\/homicide-routier-definition-cisr\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-07-17T10:28:49+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-07-18T08:48:29+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/legipermis\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@LegiPermis\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Homicide routier : D\u00e9finition de la nouvelle mesure du gouvernement - LegiPermis\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Le gouvernement d&#039;Elisabeth Borne a annonc\u00e9 un changement de terminologie pour les accidents de la route avec des morts ou des bless\u00e9s dans certaines situations. Le terme &quot;homicide involontaire&quot; sera d\u00e9sormais remplac\u00e9 par &quot;homicide routier&quot;. Cette modification, principalement s\u00e9mantique, ne modifie pas les sanctions pr\u00e9vues par le Code p\u00e9nal et le Code de la route.\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@LegiPermis\" \/>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Homicide routier : D\u00e9finition de la nouvelle mesure du gouvernement - LegiPermis","description":"Le gouvernement d'Elisabeth Borne a annonc\u00e9 un changement de terminologie pour les accidents de la route avec des morts ou des bless\u00e9s dans certaines situations. Le terme \"homicide involontaire\" sera d\u00e9sormais remplac\u00e9 par \"homicide routier\". Cette modification, principalement s\u00e9mantique, ne modifie pas les sanctions pr\u00e9vues par le Code p\u00e9nal et le Code de la route.","canonical_url":"https:\/\/www.legipermis.com\/blog\/2023\/07\/17\/homicide-routier-definition-cisr\/","robots":"max-image-preview:large","keywords":"code de la route,code p\u00e9nal,homicide involontaire,homicide routier,s\u00e9curit\u00e9 routi\u00e8re","webmasterTools":{"miscellaneous":""},"schema":null,"og:locale":"fr_FR","og:site_name":"Auto, moto, s\u00e9curit\u00e9 routi\u00e8re et permis | blog LegiPermis |","og:type":"article","og:title":"Homicide routier : D\u00e9finition de la nouvelle mesure du gouvernement - LegiPermis","og:description":"Le gouvernement d'Elisabeth Borne a annonc\u00e9 un changement de terminologie pour les accidents de la route avec des morts ou des bless\u00e9s dans certaines situations. Le terme &quot;homicide involontaire&quot; sera d\u00e9sormais remplac\u00e9 par &quot;homicide routier&quot;. Cette modification, principalement s\u00e9mantique, ne modifie pas les sanctions pr\u00e9vues par le Code p\u00e9nal et le Code de la route.","og:url":"https:\/\/www.legipermis.com\/blog\/2023\/07\/17\/homicide-routier-definition-cisr\/","article:published_time":"2023-07-17T10:28:49+00:00","article:modified_time":"2023-07-18T08:48:29+00:00","article:publisher":"https:\/\/www.facebook.com\/legipermis\/","twitter:card":"summary","twitter:site":"@LegiPermis","twitter:title":"Homicide routier : D\u00e9finition de la nouvelle mesure du gouvernement - LegiPermis","twitter:description":"Le gouvernement d'Elisabeth Borne a annonc\u00e9 un changement de terminologie pour les accidents de la route avec des morts ou des bless\u00e9s dans certaines situations. Le terme &quot;homicide involontaire&quot; sera d\u00e9sormais remplac\u00e9 par &quot;homicide routier&quot;. Cette modification, principalement s\u00e9mantique, ne modifie pas les sanctions pr\u00e9vues par le Code p\u00e9nal et le Code de la route.","twitter:creator":"@LegiPermis"},"aioseo_meta_data":{"post_id":"12193","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-07-17 09:45:54","updated":"2023-07-18 08:48:29","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.legipermis.com\/blog\" title=\"Accueil\">Accueil<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.legipermis.com\/blog\/category\/legislation\/\" title=\"L\u00e9gislation du code de la route et du permis de conduire\">L\u00e9gislation du code de la route et du permis de conduire<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tHomicide routier : D\u00e9finition de la nouvelle mesure du gouvernement\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Accueil","link":"https:\/\/www.legipermis.com\/blog"},{"label":"L\u00e9gislation du code de la route et du permis de conduire","link":"https:\/\/www.legipermis.com\/blog\/category\/legislation\/"},{"label":"Homicide routier : D\u00e9finition de la nouvelle mesure du gouvernement","link":"https:\/\/www.legipermis.com\/blog\/2023\/07\/17\/homicide-routier-definition-cisr\/"}],"_links":{"self":[{"href":"https:\/\/www.legipermis.com\/blog\/wp-json\/wp\/v2\/posts\/12193","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.legipermis.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.legipermis.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.legipermis.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.legipermis.com\/blog\/wp-json\/wp\/v2\/comments?post=12193"}],"version-history":[{"count":0,"href":"https:\/\/www.legipermis.com\/blog\/wp-json\/wp\/v2\/posts\/12193\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.legipermis.com\/blog\/wp-json\/wp\/v2\/media\/12206"}],"wp:attachment":[{"href":"https:\/\/www.legipermis.com\/blog\/wp-json\/wp\/v2\/media?parent=12193"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.legipermis.com\/blog\/wp-json\/wp\/v2\/categories?post=12193"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.legipermis.com\/blog\/wp-json\/wp\/v2\/tags?post=12193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}